{"id":216,"date":"2022-01-31T11:29:22","date_gmt":"2022-01-31T10:29:22","guid":{"rendered":"https:\/\/www.g7international.info\/cerisie\/?page_id=216"},"modified":"2025-05-16T16:45:20","modified_gmt":"2025-05-16T14:45:20","slug":"referenzmaterialien","status":"publish","type":"page","link":"https:\/\/www.cerisie.it\/de\/fornitura-di-materiali-di-riferimento\/","title":{"rendered":"REFERENZMATERIALIEN"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"216\" class=\"elementor elementor-216\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-725b3a5 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"725b3a5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53196533\" data-id=\"53196533\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ec75d9d elementor-widget elementor-widget-heading\" data-id=\"1ec75d9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REFERENZMATERIALIEN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-341a28c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"341a28c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-66f92ab\" data-id=\"66f92ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1583bc elementor-widget elementor-widget-text-editor\" data-id=\"d1583bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CERISIE bietet zertifizierte Materialien f\u00fcr die Durchf\u00fchrung von Pr\u00fcfungen an:<\/p><ul><li>Lieferung von S\u00e4tzen zertifizierter Gummiproben zur \u00dcberpr\u00fcfung der Kalibrierung von Durometern<ul><li>Shore-A-H\u00e4rte<\/li><li>Shore-D-H\u00e4rte<\/li><li>Normal- und Mikro-IRHD-IRHD-H\u00e4rte<\/li><\/ul><\/li><li>Rekalibrierung zertifizierter Proben<\/li><li>Lieferung von vulkanisierten Gummiplatten f\u00fcr rotierende Trommelabriebpr\u00fcfungen (ISO 4649)<\/li><li>Lieferung von kalibriertem Schleifpapier f\u00fcr Abriebpr\u00fcfungen (ISO 4649)<\/li><li>Lieferung von Pads f\u00fcr Cesconi-Usometer (FIAT 7-M8603)<\/li><li>Lieferung von Standardmischungen<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-47c9f83\" data-id=\"47c9f83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20fb374 elementor-widget elementor-widget-image\" data-id=\"20fb374\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"534\" height=\"299\" src=\"https:\/\/www.cerisie.it\/wp-content\/uploads\/2023\/06\/materiali2.jpg\" class=\"attachment-full size-full wp-image-1461\" alt=\"\" srcset=\"https:\/\/www.cerisie.it\/wp-content\/uploads\/2023\/06\/materiali2.jpg 534w, https:\/\/www.cerisie.it\/wp-content\/uploads\/2023\/06\/materiali2-300x168.jpg 300w\" sizes=\"(max-width: 534px) 100vw, 534px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Materiali di riferimento Il CERISIE fornisce materiali certificati per l&#8217;esecuzione di prove: Fornitura set di provini in gomma certificati per il controllo della taratura dei durometri Durezza Shore A Durezza Shore D Durezza IRHD normale e microIRHD Ritaratura dei provini certificati Fornitura di placche in gomma vulcanizzata per test di abrasione a tamburo cilindrico rotante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-216","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/pages\/216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/comments?post=216"}],"version-history":[{"count":1,"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/pages\/216\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/pages\/216\/revisions\/1574"}],"wp:attachment":[{"href":"https:\/\/www.cerisie.it\/de\/wp-json\/wp\/v2\/media?parent=216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}